{"id":2586,"date":"2017-08-14T23:47:07","date_gmt":"2017-08-14T21:47:07","guid":{"rendered":"http:\/\/leavicens.com\/?p=2586"},"modified":"2017-08-15T00:02:11","modified_gmt":"2017-08-14T22:02:11","slug":"lea-vicens-vuelve-a-reconquistar-huesca-tres-orejas-y-nueva-puerta-grande","status":"publish","type":"post","link":"https:\/\/leavicens.com\/en_US\/lea-vicens-vuelve-a-reconquistar-huesca-tres-orejas-y-nueva-puerta-grande\/","title":{"rendered":"L\u00c9A VICENS, RECONQUISTA HUESCA. TRES OREJAS Y NUEVA PUERTA GRANDE"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong><u>MUNDOTORO<\/u><\/strong><\/p>\n<p><strong>Andy y L\u00e9a Vicens, en figura, broche de oro<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cLos rejones cerraban la\u00a0<strong style=\"font-style: inherit;\">Albahaca<\/strong>, una corrida de\u00a0<strong style=\"font-style: inherit;\">Passanha<\/strong>\u00a0que ofreci\u00f3 escaso juego en general, a excepci\u00f3n de los dos toros que tocaron en suerte a\u00a0<strong style=\"font-style: inherit;\">Lea Vicens<\/strong>\u00a0que consigui\u00f3 sumar tres trofeos en una destacada actuaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El toro que cerraba la feria oscense pesaba 590 kilos y barbe\u00f3 tablas de salida. Lo par\u00f3 montando a\u00a0<strong style=\"font-style: inherit;\">\u2018Petit-pois\u2019<\/strong>\u00a0y entusiasm\u00f3 poniendo palos con<strong style=\"font-style: inherit;\">\u2018Gacela\u2019<\/strong>, dej\u00e1ndose llegar mucho a lomos de\u00a0<strong style=\"font-style: inherit;\">\u2018Deseado\u2019<\/strong>. Puso cortas con\u00a0<strong style=\"font-style: inherit;\">\u2018Jazm\u00edn\u2019<\/strong>\u00a0y mat\u00f3 f\u00e1cil de nuevo con\u00a0<strong style=\"font-style: inherit;\">\u2018Espont\u00e1neo\u2019<\/strong>, cortando las dos orejas.<\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-style: inherit;\">Lea Vicens<\/strong>\u00a0par\u00f3 con\u00a0<strong style=\"font-style: inherit;\">\u2018Guitarra\u2019<\/strong>\u00a0un toro que embest\u00eda mejor que sus hermanos sin ser un dechado de bravura. Puso banderillas con\u00a0<strong style=\"font-style: inherit;\">\u2018B\u00e9tico\u2019<\/strong>,\u00a0<strong style=\"font-style: inherit;\">\u2018Bazoka\u2019<\/strong>\u00a0y<strong style=\"font-style: inherit;\">\u00a0\u2018Greco\u2019.<\/strong>\u00a0Mat\u00f3 mal con<strong style=\"font-style: inherit;\">\u00a0\u2018Espont\u00e1neo\u2019<\/strong>. Se gan\u00f3 al p\u00fablico con su forma alegre de montar y pase\u00f3 la primera oreja de la tarde\u201d.<\/p>\n<p><u>Fuente:<\/u>\u00a0http:\/\/www.mundotoro.com\/noticia\/andy-cartagena-sergio-galan-y-lea-vicens-al-detalle\/1339464<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>LA VANGUARDIA \/ AGENCIA EFE<\/u><\/strong><\/p>\n<p><strong>Andy Cartagena y Lea Vicens, a hombros en la \u00faltima de feria en Huesca<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cLos rejoneadores\u00a0<strong style=\"font-style: inherit;\">Andy Cartagena y Lea Vicens<\/strong>\u00a0salieron por la puerta grande en el quinta y \u00faltima corrida de la\u00a0<strong style=\"font-style: inherit;\">Feria de la Albahaca de Huesca<\/strong>\u00a0tras cortar dos y tres orejas, respectivamente, en una tarde aciaga para Sergio Gal\u00e1n.<\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-style: inherit;\">La triunfadora de la tarde en Huesca fue la francesa Lea Vicens<\/strong>\u00a0con una oreja en el primero de su lote, y dos en el que cerraba plaza mostrando que progresa en el arte del rejoneo con detalles interesante sobre los caballos\u201d.<\/p>\n<p><u>Fuente:<\/u>\u00a0http:\/\/www.lavanguardia.com\/vida\/20170814\/43572821428\/andy-cartagena-y-lea-vicens-a-hombros-en-la-ultima-de-feria-en-huesca.html<\/p>\n<p><strong style=\"font-style: inherit;\"><u>FICHA DEL FESTEJO<\/u><\/strong><\/p>\n<p>Plaza de toros de Huesca. Quinta de la feria de San Lorenzo. Corrida de rejones.<\/p>\n<p>Entrada: Tres cuartos de plaza.<\/p>\n<p>Se lidiaron toros de\u00a0<strong style=\"font-style: inherit;\">Passanha<\/strong>, desiguales de presentaci\u00f3n y de escaso juego.<\/p>\n<p>Andy Cartagena; Silencio y dos orejas.<\/p>\n<p>Sergio Gal\u00e1n; Ovaci\u00f3n y silencio.<\/p>\n<p><strong>Lea Vicens;\u00a0Oreja y dos orejas.<\/strong><\/p>\n<p>Foto: <span style=\"text-decoration: underline;\"><strong>Aplausos<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; MUNDOTORO Andy y L\u00e9a Vicens, en figura, broche de oro \u201cLos rejones cerraban la\u00a0Albahaca, una corrida de\u00a0Passanha\u00a0que ofreci\u00f3 escaso&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2592,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[20,1],"tags":[],"_links":{"self":[{"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/posts\/2586"}],"collection":[{"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/comments?post=2586"}],"version-history":[{"count":3,"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/posts\/2586\/revisions"}],"predecessor-version":[{"id":2593,"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/posts\/2586\/revisions\/2593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/media\/2592"}],"wp:attachment":[{"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/media?parent=2586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/categories?post=2586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leavicens.com\/en_US\/wp-json\/wp\/v2\/tags?post=2586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}