{"id":2703,"date":"2017-09-10T22:16:33","date_gmt":"2017-09-10T20:16:33","guid":{"rendered":"http:\/\/leavicens.com\/?p=2703"},"modified":"2017-09-22T21:04:32","modified_gmt":"2017-09-22T19:04:32","slug":"lea-vicens-broche-de-oro-en-valladolid-nueva-conquista-con-dos-orejas","status":"publish","type":"post","link":"https:\/\/leavicens.com\/fr_FR\/lea-vicens-broche-de-oro-en-valladolid-nueva-conquista-con-dos-orejas\/","title":{"rendered":"L\u00c9A VICENS, PUERTA GRANDE EN VALLADOLID CON DOS OREJAS"},"content":{"rendered":"<p><strong><u>MUNDOTORO<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u201c<\/strong>Manuel Manzanares\u00a0y<strong>\u00a0Lea Vicens<\/strong>\u00a0pusieron el broche de oro a la Feria de Nuestra Se\u00f1ora de San Lorenzo de\u00a0Valladolid. Ambos exhibieron sus facultades y cortaron dos orejas cada uno abriendo la Puerta Grande de un buen lote de\u00a0Ferm\u00edn Boh\u00f3rquez.<\/p>\n<p style=\"text-align: justify;\"><strong>Lea Vicens<\/strong>\u00a0pase\u00f3 una oreja del tercero, un toro noble al que instrument\u00f3 una faena elegante, templada y elegante.\u00a0La francesa remat\u00f3 su tarde cortando otra oreja. Faena de temple, clasicismo y elegancia de muy buen corte en la que se vio su evoluci\u00f3n\u201d.<\/p>\n<p><u>Fuente:<\/u> http:\/\/www.mundotoro.com\/noticia\/la-ultima-de-valladolid-al-detalle-1343834\/1343840<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>APLAUSOS<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Lea Vicens<\/strong> tambi\u00e9n logr\u00f3 cortar un trofeo al noble tercero tras una actuaci\u00f3n en la que volvi\u00f3 a dejar muestras del concepto puro de su toreo. Seria, templada y elegante tanto en la preparaci\u00f3n de las suertes como en su ejecuci\u00f3n. Su actuaci\u00f3n fue premiada con una oreja. Cerr\u00f3 el festejo y la feria la amazona francesa, quien al igual que Manzanares logr\u00f3 cortar un nuevo trofeo tras lograr cuajar una faena en la que volvi\u00f3 a mostrar su madurez y progreso. Toreo elegante, doma cl\u00e1sica, suave y honda compusieron una actuaci\u00f3n redonda y muy interesante premiada con una oreja y la consiguiente puerta grande\u201d.<\/p>\n<p><u>Fuente:<\/u> https:\/\/www.aplausos.es\/noticia\/40962\/noticias\/manzanares-y-lea-vicens-broche-de-oro-en-valladolid.html<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>TRIBUNA DE VALLADOLID<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cSe presentaba en el Coso de Zorrilla la rejoneadora <strong>Lea Vicens, <\/strong>acompa\u00f1ada por el incombustible<strong>\u00a0<\/strong>\u00c1ngel Peralta,\u00a0su maestro.<strong>\u00a0<\/strong>Exhibi\u00f3 una gran cuadra y muchas ganas en una tarde en la que tambi\u00e9n logr\u00f3 arrancar una oreja a cada uno de sus enemigos. El que hac\u00eda tercero fue manso, aunque con los rejones de castigo se creci\u00f3 y sac\u00f3 un punto de casta que la francesa lo aprovech\u00f3 con una lidia muy efectista, aunque hubo varios pasajes en los que consinti\u00f3 mucho al de\u00a0Ferm\u00edn Boh\u00f3rquez para ajustarse en banderillas.<\/p>\n<p style=\"text-align: justify;\">El que cerraba tarde y feria fue m\u00e1s noble, a pesar de su salida abanta<strong>.<\/strong> Se adorn\u00f3 la rejoneadora en algunos embroques<strong>,\u00a0logr\u00f3 momentos vibrantes encima de sus cabalgaduras.<\/strong>\u00a0El rej\u00f3n final volvi\u00f3 a ser efectivo y el p\u00fablico, que no lleg\u00f3 a cubrir la mitad del aforo, pidi\u00f3 con fuerza la segunda oreja que permit\u00eda a la rejoneadora\u00a0abrir la Puerta Grande junto a Manzanares\u201d.<\/p>\n<p><strong><u>Fuente:<\/u><\/strong> https:\/\/www.tribunavalladolid.com\/noticias\/manzanares-y-vicens-ponen-la-puerta-grande-hermoso-de-mendoza-el-toreo-a-caballo\/1505071342<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong><u>FICHA DEL FESTEJO<\/u><\/strong><\/p>\n<p><strong>Valladolid<\/strong>, 10 de septiembre de 2017.<\/p>\n<p>Entrada:\u00a0Alrededor de media plaza<strong>.<\/strong><\/p>\n<p>Toros de<strong>\u00a0<\/strong>Ferm\u00edn Boh\u00f3rquez,\u00a0nobles en l\u00edneas generales.<strong>\u00a0<\/strong><\/p>\n<p>Hermoso de Mendoza, Silencio y oreja<strong>;<\/strong><\/p>\n<p>Manuel Manzanares; Oreja en ambos<strong>;<\/strong><\/p>\n<p><strong>Lea Vicens<\/strong>; Oreja en ambos<strong>. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MUNDOTORO \u201cManuel Manzanares\u00a0y\u00a0Lea Vicens\u00a0pusieron el broche de oro a la Feria de Nuestra Se\u00f1ora de San Lorenzo de\u00a0Valladolid. Ambos exhibieron&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2704,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[20,1],"tags":[],"_links":{"self":[{"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/posts\/2703"}],"collection":[{"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/comments?post=2703"}],"version-history":[{"count":3,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/posts\/2703\/revisions"}],"predecessor-version":[{"id":2754,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/posts\/2703\/revisions\/2754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/media\/2704"}],"wp:attachment":[{"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/media?parent=2703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/categories?post=2703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/tags?post=2703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}