{"id":3327,"date":"2018-03-16T09:48:22","date_gmt":"2018-03-16T08:48:22","guid":{"rendered":"http:\/\/leavicens.com\/?p=3327"},"modified":"2018-03-17T13:48:56","modified_gmt":"2018-03-17T12:48:56","slug":"la-borrasca-gisele-obliga-a-aplazar-el-festejo-de-andujar","status":"publish","type":"post","link":"https:\/\/leavicens.com\/fr_FR\/la-borrasca-gisele-obliga-a-aplazar-el-festejo-de-andujar\/","title":{"rendered":"&#8216;GISELE&#8217; OBLIGA A APLAZAR EL FESTEJO DE HOY, 17.03 EN ANDUJAR, PARA EL 07.04"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>\u201cSe celebrar\u00e1 el s\u00e1bado 7 de abril, con el mismo cartel\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">Desde el mi\u00e9rcoles 14,\u00a0<strong style=\"font-style: inherit;\">And\u00fajar (Ja\u00e9n) est\u00e1 recibiendo a \u2018Gisele\u2019,<\/strong>\u00a0<strong>la nueva borrasca atl\u00e1ntica<\/strong> que, seg\u00fan\u00a0<strong style=\"font-style: inherit;\">las previsiones de la AEMET,<\/strong>\u00a0este s\u00e1bado va a continuar en la localidad jienense, y como consecuencia se esperan numerosas lluvias y fuerte viento.<\/p>\n<p style=\"text-align: justify;\">Es por lo que, tanto\u00a0<strong style=\"font-style: inherit;\">Ayuntamiento como empresa,<\/strong>\u00a0han preferido anunciar con suficiente antelaci\u00f3n, que la \u2018<strong style=\"font-style: inherit;\">Corrida de Toros Mixta\u2019<\/strong>\u00a0que se iba a celebrar este\u00a0<strong style=\"font-style: inherit;\">s\u00e1bado (17 de marzo)<\/strong>\u00a0como comienzo de la temporada taurina,\u00a0<strong style=\"font-style: inherit;\">va a ser aplazada<\/strong> para que as\u00ed de esa manera, el mucho p\u00fablico y aficionados que ya hab\u00edan adquirido sus entradas para este festejo, y que se iban a desplazar a la capital de la Campi\u00f1a de Ja\u00e9n para presenciar el festejo, cambien sus planes para la nueva fecha de celebraci\u00f3n de la misma.<\/p>\n<p style=\"text-align: justify;\"><strong>As\u00ed, el 7 de abril, s\u00e1bado, es la nueva fecha<\/strong> en la que estar\u00e1n presentes en el <strong>Coso Iliturgitano\u00a0<\/strong>la rejoneadora, <strong>Lea Vicens,<\/strong> y los matadores de toros, <strong>Manuel D\u00edaz \u2018El Cordob\u00e9s\u2019, David Fandila \u2018El Fandi\u2019<\/strong> y <strong>Julio Ben\u00edtez \u2018El Cordob\u00e9s\u2019<\/strong>; que se las entender\u00e1n con un toro de <strong>Peralta<\/strong> (para rejones), y seis de <strong>Rom\u00e1n Sorando<\/strong>, para lidia a pie.<\/p>\n<p><a href=\"http:\/\/leavicens.com\/lvicens\/wp-content\/uploads\/2018\/03\/Cartel-And--jar.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-3262 aligncenter\" src=\"http:\/\/leavicens.com\/lvicens\/wp-content\/uploads\/2018\/03\/Cartel-And--jar-144x300.jpg\" alt=\"\" width=\"144\" height=\"300\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSe celebrar\u00e1 el s\u00e1bado 7 de abril, con el mismo cartel\u201d Desde el mi\u00e9rcoles 14,\u00a0And\u00fajar (Ja\u00e9n) est\u00e1 recibiendo a \u2018Gisele\u2019,\u00a0la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":3328,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[20,1],"tags":[],"_links":{"self":[{"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/posts\/3327"}],"collection":[{"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/comments?post=3327"}],"version-history":[{"count":6,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/posts\/3327\/revisions"}],"predecessor-version":[{"id":3334,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/posts\/3327\/revisions\/3334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/media\/3328"}],"wp:attachment":[{"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/media?parent=3327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/categories?post=3327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leavicens.com\/fr_FR\/wp-json\/wp\/v2\/tags?post=3327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}